{"id":35100,"date":"2025-10-13T14:05:52","date_gmt":"2025-10-13T18:05:52","guid":{"rendered":"\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front.png"},"modified":"2026-03-26T10:05:09","modified_gmt":"2026-03-26T14:05:09","slug":"kids-mighty-mix-front-2","status":"inherit","type":"attachment","link":"\/es\/bravenly-kids-mighty-mix\/kids-mighty-mix-front-2\/","title":{"rendered":"Kids Mighty Mix Front"},"author":191432663,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-35100","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https://d1jeyrxw15fk4e.cloudfront.net/es/https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front.png'><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-232x300.png\" class=\"attachment-medium size-medium\" alt=\"Kids Mighty Mix Front\" srcset=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-232x300.png 232w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-791x1024.png 791w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-768x994.png 768w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1187x1536.png 1187w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1080x1398.png 1080w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-400x516.png 400w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1280x1657.png 1280w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-980x1269.png 980w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-480x621.png 480w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front.png 1545w\" sizes=\"(max-width: 232px) 100vw, 232px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Kids Mighty Mix Front","media_type":"image","mime_type":"image\/png","media_details":{"width":1545,"height":2000,"file":"2025\/10\/Kids-Mighty-Mix-Front.png","filesize":1060175,"sizes":{"medium":{"file":"Kids-Mighty-Mix-Front-232x300.png","width":232,"height":300,"filesize":30682,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-232x300.png"},"large":{"file":"Kids-Mighty-Mix-Front-791x1024.png","width":791,"height":1024,"filesize":277067,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-791x1024.png"},"thumbnail":{"file":"Kids-Mighty-Mix-Front-150x150.png","width":150,"height":150,"filesize":14731,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-150x150.png"},"medium_large":{"file":"Kids-Mighty-Mix-Front-768x994.png","width":768,"height":994,"filesize":259858,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-768x994.png"},"1536x1536":{"file":"Kids-Mighty-Mix-Front-1187x1536.png","width":1187,"height":1536,"filesize":599644,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1187x1536.png"},"et-pb-post-main-image":{"file":"Kids-Mighty-Mix-Front-400x250.png","width":400,"height":250,"filesize":76129,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-400x250.png"},"et-pb-post-main-image-fullwidth":{"file":"Kids-Mighty-Mix-Front-1080x675.png","width":1080,"height":675,"filesize":494221,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1080x675.png"},"et-pb-portfolio-image":{"file":"Kids-Mighty-Mix-Front-400x284.png","width":400,"height":284,"filesize":76689,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-400x284.png"},"et-pb-portfolio-module-image":{"file":"Kids-Mighty-Mix-Front-510x382.png","width":510,"height":382,"filesize":120282,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-510x382.png"},"et-pb-portfolio-image-single":{"file":"Kids-Mighty-Mix-Front-1080x1398.png","width":1080,"height":1398,"filesize":501401,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1080x1398.png"},"et-pb-gallery-module-image-portrait":{"file":"Kids-Mighty-Mix-Front-400x516.png","width":400,"height":516,"filesize":78237,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-400x516.png"},"et-pb-post-main-image-fullwidth-large":{"file":"Kids-Mighty-Mix-Front-1545x1800.png","width":1545,"height":1800,"filesize":1040666,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1545x1800.png"},"et-pb-image--responsive--desktop":{"file":"Kids-Mighty-Mix-Front-1280x1657.png","width":1280,"height":1657,"filesize":690453,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-1280x1657.png"},"et-pb-image--responsive--tablet":{"file":"Kids-Mighty-Mix-Front-980x1269.png","width":980,"height":1269,"filesize":417396,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-980x1269.png"},"et-pb-image--responsive--phone":{"file":"Kids-Mighty-Mix-Front-480x621.png","width":480,"height":621,"filesize":107885,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-480x621.png"},"cmplz_banner_image":{"file":"Kids-Mighty-Mix-Front-350x100.png","width":350,"height":100,"filesize":32043,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front-350x100.png"},"full":{"file":"Kids-Mighty-Mix-Front.png","width":1545,"height":2000,"mime_type":"image\/png","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":36292,"source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/10\/Kids-Mighty-Mix-Front.png","filename":"Kids-Mighty-Mix-Front.png","filesize":1060175,"_links":{"self":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media\/35100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/users\/191432663"}],"replies":[{"embeddable":true,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/comments?post=35100"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":36292,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/pages\/36292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}