{"id":37279,"date":"2025-11-05T16:12:07","date_gmt":"2025-11-05T21:12:07","guid":{"rendered":"\/wp-content\/uploads\/2025\/11\/GLOW.jpg"},"modified":"2025-11-05T16:12:07","modified_gmt":"2025-11-05T21:12:07","slug":"glow-3","status":"inherit","type":"attachment","link":"\/es\/bravenly-glow\/glow-3\/","title":{"rendered":"GLOW"},"author":191432657,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":""},"class_list":["post-37279","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https://d1jeyrxw15fk4e.cloudfront.net/es/https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-232x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-232x300.jpg 232w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-791x1024.jpg 791w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-768x994.jpg 768w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1187x1536.jpg 1187w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1080x1398.jpg 1080w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-400x516.jpg 400w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1280x1657.jpg 1280w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-980x1269.jpg 980w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-480x621.jpg 480w, https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW.jpg 1545w\" sizes=\"(max-width: 232px) 100vw, 232px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1545,"height":2000,"file":"2025\/11\/GLOW.jpg","filesize":308049,"sizes":{"medium":{"file":"GLOW-232x300.jpg","width":232,"height":300,"filesize":18322,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-232x300.jpg"},"large":{"file":"GLOW-791x1024.jpg","width":791,"height":1024,"filesize":125901,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-791x1024.jpg"},"thumbnail":{"file":"GLOW-150x150.jpg","width":150,"height":150,"filesize":8332,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-150x150.jpg"},"medium_large":{"file":"GLOW-768x994.jpg","width":768,"height":994,"filesize":122643,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-768x994.jpg"},"1536x1536":{"file":"GLOW-1187x1536.jpg","width":1187,"height":1536,"filesize":213760,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1187x1536.jpg"},"et-pb-post-main-image":{"file":"GLOW-400x250.jpg","width":400,"height":250,"filesize":32215,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-400x250.jpg"},"et-pb-post-main-image-fullwidth":{"file":"GLOW-1080x675.jpg","width":1080,"height":675,"filesize":126709,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1080x675.jpg"},"et-pb-portfolio-image":{"file":"GLOW-400x284.jpg","width":400,"height":284,"filesize":36503,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-400x284.jpg"},"et-pb-portfolio-module-image":{"file":"GLOW-510x382.jpg","width":510,"height":382,"filesize":56932,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-510x382.jpg"},"et-pb-portfolio-image-single":{"file":"GLOW-1080x1398.jpg","width":1080,"height":1398,"filesize":189965,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1080x1398.jpg"},"et-pb-gallery-module-image-portrait":{"file":"GLOW-400x516.jpg","width":400,"height":516,"filesize":47392,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-400x516.jpg"},"et-pb-post-main-image-fullwidth-large":{"file":"GLOW-1545x1800.jpg","width":1545,"height":1800,"filesize":311372,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1545x1800.jpg"},"et-pb-image--responsive--desktop":{"file":"GLOW-1280x1657.jpg","width":1280,"height":1657,"filesize":238154,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-1280x1657.jpg"},"et-pb-image--responsive--tablet":{"file":"GLOW-980x1269.jpg","width":980,"height":1269,"filesize":168833,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-980x1269.jpg"},"et-pb-image--responsive--phone":{"file":"GLOW-480x621.jpg","width":480,"height":621,"filesize":63347,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-480x621.jpg"},"cmplz_banner_image":{"file":"GLOW-350x100.jpg","width":350,"height":100,"filesize":12740,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW-350x100.jpg"},"full":{"file":"GLOW.jpg","width":1545,"height":2000,"mime_type":"image\/jpeg","source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":15389,"source_url":"https:\/\/d1jeyrxw15fk4e.cloudfront.net\/wp-content\/uploads\/2025\/11\/GLOW.jpg","filename":"GLOW.jpg","filesize":308049,"_links":{"self":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media\/37279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/users\/191432657"}],"replies":[{"embeddable":true,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/comments?post=37279"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":15389,"href":"https:\/\/menaaa73.bravenlyglobal.com\/es\/wp-json\/wp\/v2\/pages\/15389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}